{"id":4974,"date":"2025-11-28T15:37:04","date_gmt":"2025-11-28T20:37:04","guid":{"rendered":"https:\/\/highway413.ca\/fr\/?page_id=4974"},"modified":"2026-04-27T15:27:46","modified_gmt":"2026-04-27T19:27:46","slug":"rere","status":"publish","type":"page","link":"https:\/\/highway413.ca\/fr\/rere\/","title":{"rendered":"Rapport d&rsquo;\u00e9valuation des r\u00e9percussions environnementales"},"content":{"rendered":"\n\n\t<a href=\"https:\/\/highway413.ca\/en\/eiar\/\" target=\"_self\" role=\"button\" aria-label=\"English\">\n\t\t\t\t\t\tEnglish\n\t\t\t\t\t<\/a>\n\t\t<h1>\n\t\t\tRapport d&rsquo;\u00e9valuation des r\u00e9percussions environnementales\n\t\t<\/h1>\n<h2  id=\"rere\">\n\t\t\tRapport d&rsquo;\u00e9valuation des r\u00e9percussions environnementales (RERE)\t<\/h2>\n\t<p>Le rapport pr\u00e9liminaire d&rsquo;\u00e9valuation des r\u00e9percussions environnementales (RERE) \u00e9tait disponible sur le site internet du projet pour commentaires entre le <strong>1<sup>er<\/sup> d\u00e9cembre 2025<\/strong> et le <strong>6 janvier 2026<\/strong>.<\/p>\n<p>Le minist\u00e8re des Transports a mis \u00e0 jour le rapport pr\u00e9liminaire conform\u00e9ment \u00e0 l&rsquo;<strong>article 8<\/strong> de la <em>Loi sur l&rsquo;autoroute 413, 2024<\/em>. Toutes les pr\u00e9occupations soulev\u00e9es pendant la p\u00e9riode de consultation publique par le public, les organismes f\u00e9d\u00e9raux et provinciaux, les repr\u00e9sentants municipaux, les communaut\u00e9s autochtones et les autres personnes int\u00e9ress\u00e9es ont \u00e9t\u00e9 examin\u00e9es et r\u00e9sum\u00e9es dans le rapport final d&rsquo;\u00e9valuation environnementale.<\/p>\n<p>Le rapport comprend les informations suivantes :<\/p>\n<figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Highway413-Final-EIAR.jpg\" alt=\"Page couverture du Rapport final d'\u00e9valuation des impacts environnementaux du projet Highway\u202f413, mars\u202f2026, avec les logos du gouvernement de l'Ontario, de WSP et d'AECOM.\" height=\"1294\" width=\"2023\" title=\"Highway413-Final-EIAR\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t<\/figure>\n\t\t<ul>\n\t\t\t\t\t<li>\n\t\t\t\t<h4>Description de l&rsquo;autoroute 413 <\/h4>\n\t\t<ul><li>Une d\u00e9claration sur l&rsquo;objectif du projet et une description du projet, bas\u00e9es sur la conception pr\u00e9liminaire.<\/li><\/ul>\t\t\t\n\t\t\t<\/li>\n\t\t\t\t\t<li>\n\t\t\t\t<h4>\u00c9laboration de la conception pr\u00e9liminaire<\/h4>\n\t\t<ul><li>Cartes indiquant l&#8217;emplacement et la conception pr\u00e9liminaire du projet de l&rsquo;autoroute 413, y compris les prolongements des autoroutes 410 et 427<\/li><li>Descriptions des diff\u00e9rentes options envisag\u00e9es pour le projet de l&rsquo;autoroute 413 ainsi que les raisons qui ont motiv\u00e9 le choix du trac\u00e9 actuel<\/li><\/ul>\t\t\t\n\t\t\t<\/li>\n\t\t\t\t\t<li>\n\t\t\t\t<h4>Consid\u00e9rations environnementales<\/h4>\n\t\t<ul><li>Un r\u00e9sum\u00e9 des conditions environnementales locales<\/li><li>Une description des \u00e9tudes environnementales r\u00e9alis\u00e9es pour le projet, des r\u00e9percussions environnementales potentielles et des mesures d&rsquo;att\u00e9nuation propos\u00e9es<\/li><li>Une description de la mani\u00e8re dont les mesures d&rsquo;att\u00e9nuation seront mises en \u0153uvre, \u00e9valu\u00e9es et surveill\u00e9es au cours des phases de conception futures<\/li><li>Une liste des autorisations provinciales, f\u00e9d\u00e9rales ou autres qui pourraient \u00eatre requises pour le projet<\/li><\/ul>\t\t\t\n\t\t\t<\/li>\n\t\t\t\t\t<li>\n\t\t\t\t<h4>Consultation et engagement<\/h4>\n\t\t<ul><li>Un compte rendu des consultations et des engagements avec les organismes de r\u00e9glementation, le public, les parties prenantes et les communaut\u00e9s autochtones<\/li><\/ul>\t\t\t\n\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t<p>La publication du rapport final d&rsquo;\u00e9valuation des r\u00e9percussions environnementales (RERE) marque la fin de la phase de conception pr\u00e9liminaire du projet de l&rsquo;autoroute 413. Le projet passera \u00e0 la phase de conception d\u00e9taill\u00e9e, qui comprendra des ajustements suppl\u00e9mentaires et la suite des consultations. Le RERE ainsi que les rapports d&rsquo;\u00e9valuation des r\u00e9percussions pour chaque discipline sont disponibles ci-dessous.<\/p>\n<p>Conform\u00e9ment \u00e0 l&rsquo;<strong>article 8<\/strong> de la <em>loi sur l&rsquo;autoroute 413 de 2024<\/em>, le rapport final d&rsquo;\u00e9valuation des r\u00e9percussions environnementales a \u00e9t\u00e9 publi\u00e9 sur le site internet du projet le <strong>11 mars 2026<\/strong>.<\/p>\n\t\t\t\tDocuments du rapport d&rsquo;\u00e9valuation des r\u00e9percussions environnementales\n\t\t\t\t\t<ul>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Avis-RERE-final_Mars2026.pdf\">Avis de publication du rapport final d&rsquo;\u00e9valuation des r\u00e9percussions<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Highway-413-Final-EIAR_web-version_Mar2026.pdf\">Rapport final d&rsquo;\u00e9valuation des r\u00e9percussions environnementales<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Appendix-A-Compiled_Mar2026.pdf\">Annexe A<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Appendix-B-Compiled_Mar2026.pdf\">Annexe B<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Appendix-C-Compiled_Mar2026.pdf\">Annexe C<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/en\/wp-content\/uploads\/2026\/03\/Hwy-413-AODA-Fisheries-IA_2026-03-19_Compiled.pdf\">Rapport d&rsquo;\u00e9valuation des r\u00e9percussions sur les poissons et leur habitat, 2026<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/en\/wp-content\/uploads\/2026\/03\/Hwy-413-AODA-Terrestrial-Ecosystems-IA_2026-03-19-compiled.pdf\">Rapport d&rsquo;\u00e9valuation des r\u00e9percussions sur les \u00e9cosyst\u00e8mes terrestres, 2026<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Highway-413-Hydrogeological-Report-Rev1_20260319-locked.pdf\">Rapport hydrog\u00e9ologique, 2026<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Hwy-413-ESORA-Memo-Final-March-12-2026.pdf\">Note technique d&rsquo;\u00e9valuation des risques li\u00e9s \u00e0 l&rsquo;\u00e9rosion et \u00e0 la s\u00e9dimentation , 2026<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Highway-413-Climate-Change-Analysis-Report_Revised-Final-March-20-2026.pdf\">Rapport d&rsquo;analyse sur les changements climatiques, 2026<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Hwy-413_AODA-CHAR_2026-03-19-compiled.pdf\">Rapport d&rsquo;\u00e9valuation du patrimoine culturel, 2026<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/01_Hwy-413_AODA_Drainage-CH_SWM_2026-03-19-compiled.pdf\">Rapport sur le drainage et la gestion des eaux pluviales &#8211; Section ouest de la r\u00e9gion de conservation de Halton, 2026<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/02_Hwy-413_AODA_Drainage-CVC_SWM_2026-03-19-compiled.pdf\">Rapport sur le drainage et la gestion des eaux pluviales &#8211; R\u00e9gion de conservation de la vall\u00e9e de la rivi\u00e8re Credit Ouest, 2026<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/en\/wp-content\/uploads\/2026\/03\/03_Hwy%20413_Drainage%20TRCA_SWM_2026-03-19%20compiled.pdf\">Rapport sur le drainage et la gestion des eaux pluviales &#8211; R\u00e9gion de l&rsquo;Office de protection de la nature de Toronto et de la r\u00e9gion, 2026<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/04\/Hwy-413-AODA-Fluvial-Geomorphological_2026-04-02-Protected_Optimized.pdf\">Rapport d&rsquo;\u00e9valuation g\u00e9omorphologique fluviale, 2026<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/04\/Highway-413_Agriculture-Impact-Assessment-Report_08Apr2026.pdf\">Rapport d&rsquo;\u00e9valuation des r\u00e9percussions sur l&rsquo;agriculture, 2026<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/04\/Highway-413-Community-Wellbeing-Report-Combined.pdf\">Rapport sur le bien\u2011\u00eatre de la communaut\u00e9, 2026<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/04\/20251202-RWDI-1301992-REP-Snowdrifting-Hwy413.pdf\">Rapport d&rsquo;\u00e9valuation des cong\u00e8res, 2025<\/a><\/li>\n<li><a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/04\/20260325_2044-RWDI-1301992A-REP-AirQuality-Hwy413.pdf\">Rapport d&rsquo;\u00e9valuation des r\u00e9percussions sur la qualit\u00e9 de l&rsquo;air, 2026<\/a><\/li>\n<\/ul>\n<h2  id=\"comment\">\n\t\t\tComment soumettre un commentaire\t<\/h2>\n\t<p>Le <strong>RERE pr\u00e9liminaire<\/strong> sera disponible pour commentaires sur le site internet du projet du <strong>1er d\u00e9cembre 2025<\/strong> au <strong>6 janvier 2026 \u00e0 23 h 59<\/strong>.<\/p>\n<p>Les commentaires sur le RERE pr\u00e9liminaire peuvent \u00eatre soumis des fa\u00e7ons suivantes :<\/p>\n<ul>\n<li><strong>Site web du projet:<\/strong> <a href=\"#formulaire\">Zone de commentaires ci-dessous<\/a><\/li>\n<li><strong>Adresse courriel du projet\u00a0: <\/strong><a href=\"mailto:project_team@highway413.ca\">project_team@highway413.ca<\/a><\/li>\n<li><strong>Num\u00e9ro de t\u00e9l\u00e9phone du projet\u00a0: <\/strong>1-877-522-6916 (sans frais)<\/li>\n<\/ul>\n<p>Veuillez noter qu&rsquo;il ne sera pas possible de r\u00e9pondre \u00e0 chaque commentaire individuel. Ces informations seront conserv\u00e9es dans nos dossiers pour \u00eatre utilis\u00e9es pendant le projet et pourront \u00eatre incluses dans la documentation du projet. Les informations recueillies seront utilis\u00e9es conform\u00e9ment \u00e0 la <em>Loi sur l&rsquo;acc\u00e8s \u00e0 l&rsquo;information et la protection de la vie priv\u00e9e<\/em>.<\/p>\n<p>Veuillez nous contacter si vous avez besoin de mesures de soutien en mati\u00e8re de communication ou d&rsquo;un autre format pour acc\u00e9der \u00e0 cette information.<\/p>\n<figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2025\/11\/EIAR-form_Fr-scaled.png\" alt=\"Ordinateur portable affichant un formulaire en ligne intitul\u00e9 \u00ab Formulaire de commentaires \u00bb pour le projet de l'autoroute 413. L'en-t\u00eate vert comporte le logo stylis\u00e9 de l'autoroute 413 et le slogan \u00ab Planning with Vision | Planning for People \u00bb. Le formulaire demande des informations facultatives comme le pr\u00e9nom et le nom, avec des champs de saisie visibles.\" height=\"1536\" width=\"2560\" title=\"EIAR-form_Fr\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t<\/figure>\n<figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2024\/06\/HWY401-scaled.jpeg\"  target=\"_self\" itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2024\/06\/HWY401-scaled.jpeg\" alt=\"Autoroute tr\u00e8s fr\u00e9quent\u00e9e \u00e0 plusieurs voies avec des voitures et des camions circulant dans les deux sens. Le soleil se l\u00e8ve ou se couche derri\u00e8re la silhouette lointaine d&#039;une ville, avec des arbres bordant la route.\" height=\"1820\" width=\"2560\" title=\"View of Highway 401 in Toronto Canada  at the sun\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\t<\/figure>\n<h2  id=\"centre\">\n\t\t\tCentre d&rsquo;information sur l&rsquo;autoroute 413\t<\/h2>\n\t<p>Visitez le <strong>Centre d&rsquo;information sur l&rsquo;autoroute 413 <\/strong>pour obtenir plus d&rsquo;informations sur l&rsquo;\u00e9laboration de la conception, y compris un r\u00e9sum\u00e9 des \u00e9tudes environnementales et une carte interactive pour explorer plus en d\u00e9tail l&rsquo;autoroute 413.<\/p>\n\t\t\t<a href=\"https:\/\/vohmtohwy413fr.z27.web.core.windows.net\/\"  target=\"_self\">\n\t\t\t\t\t\t\tEn savoir plus sur le centre d&rsquo;information\n\t\t\t<\/a>\n<h2  id=\"naviguer\">\n\t\t\tComment naviguer dans le document\t<\/h2>\n\t<p>Vous trouverez ci-dessous plus d&rsquo;informations sur le contenu de chaque chapitre du RERE :<\/p>\n\t\t\t\tChapitre 1 : Aper\u00e7u du projet\n\t\t\t\t\t<p>Le chapitre 1 pr\u00e9sente le projet de l&rsquo;autoroute 413, en d\u00e9crivant son objectif et son r\u00f4le dans le r\u00e9seau de transport de l&rsquo;Ontario. Il fournit des informations g\u00e9n\u00e9rales sur le projet et met en \u00e9vidence les jalons importants. Ce chapitre explique \u00e9galement la Loi sur l&rsquo;autoroute 413, 2024 et les mesures prises pour satisfaire aux exigences l\u00e9gislatives, notamment la pr\u00e9paration et la soumission du rapport d&rsquo;\u00e9valuation des r\u00e9percussions environnementales (RERE). Enfin, le chapitre 1 pr\u00e9sente les principaux sujets abord\u00e9s dans le rapport.<\/p>\n\t\t\t\tChapitre 2 : Conditions environnementales locales et \u00e9tudes techniques\n\t\t\t\t\t<p>Le chapitre 2 pr\u00e9sente un aper\u00e7u d\u00e9taill\u00e9 des \u00e9tudes environnementales et techniques r\u00e9alis\u00e9es pour documenter le RERE. Il d\u00e9crit les \u00e9tudes, les processus de collecte de donn\u00e9es et r\u00e9sume les conditions existantes. Les informations sont organis\u00e9es en quatre grands domaines : environnement naturel, environnement social et \u00e9conomique, environnement culturel et \u00e9tudes techniques.<\/p>\n<p>La section consacr\u00e9e \u00e0 l&rsquo;<strong>environnement naturel<\/strong> examine les caract\u00e9ristiques \u00e9cologiques, notamment les poissons et leur habitat, les \u00e9cosyst\u00e8mes terrestres, les eaux souterraines et l&rsquo;hydrog\u00e9ologie, la g\u00e9omorphologie fluviale, l&rsquo;\u00e9rosion et la s\u00e9dimentation, ainsi que le drainage et la gestion des eaux pluviales.<\/p>\n<p>L&rsquo;analyse de l&rsquo;<strong>environnement social et \u00e9conomique<\/strong> porte sur l&rsquo;utilisation des terres, l&rsquo;agriculture, le paysage, le bruit, la qualit\u00e9 de l&rsquo;air, les d\u00e9chets et les propri\u00e9t\u00e9s contamin\u00e9es, les changements climatiques, le bien-\u00eatre de la communaut\u00e9 et les cong\u00e8res.<\/p>\n<p>La partie consacr\u00e9e \u00e0 l&rsquo;<strong>environnement culturel<\/strong> \u00e9value les ressources patrimoniales b\u00e2ties et les paysages patrimoniaux culturels, ainsi que l&rsquo;arch\u00e9ologie.<\/p>\n<p>Enfin, les <strong>\u00e9tudes techniques<\/strong> abordent des consid\u00e9rations techniques telles que les r\u00e9seaux routiers, les r\u00e9seaux de transport r\u00e9gionaux, les conditions de circulation existantes, les transports actifs, le transport de marchandises et les trains de banlieue, les transports publics, les eaux de surface et le drainage, les \u00e9tudes g\u00e9otechniques et les services publics.<\/p>\n\t\t\t\tChapitre 3 : Description des trac\u00e9s envisag\u00e9s et justification du choix du trac\u00e9 privil\u00e9gi\u00e9\n\t\t\t\t\t<p>Le chapitre 3 d\u00e9crit comment diff\u00e9rents trac\u00e9s routiers possibles ont \u00e9t\u00e9 \u00e9tudi\u00e9s et \u00e9valu\u00e9s, et pourquoi le trac\u00e9 privil\u00e9gi\u00e9 a \u00e9t\u00e9 choisi. Il commence par d\u00e9crire le processus par \u00e9tape utilis\u00e9 pour \u00e9valuer les options, qui a pris en compte des facteurs li\u00e9s \u00e0 la planification, \u00e0 l&rsquo;environnement et aux aspects techniques.<\/p>\n<p>La premi\u00e8re partie de ce processus a consist\u00e9 \u00e0 dresser une longue liste de trac\u00e9s envisageables qui tiraient parti des possibilit\u00e9s de transport offertes par l&rsquo;autoroute 413 et le r\u00e9seau de transport, tout en \u00e9vitant, ou lorsque cela n&rsquo;\u00e9tait pas possible, en minimisant les r\u00e9percussions sur les \u00e9l\u00e9ments environnementaux. Un processus de s\u00e9lection a ensuite \u00e9t\u00e9 entrepris afin de d\u00e9terminer les trac\u00e9s et les emplacements des \u00e9changeurs les plus favorables, en passant d&rsquo;une liste pr\u00e9liminaire \u00e0 une pr\u00e9s\u00e9lection \u00e0 l&rsquo;aide de trois principes de s\u00e9lection fondamentaux :<\/p>\n<ol>\n<li>R\u00e9duire au minimum les r\u00e9percussions sur les \u00e9l\u00e9ments et les fonctions naturels, les syst\u00e8mes et les collectivit\u00e9s importants.<\/li>\n<li>R\u00e9duire au minimum les r\u00e9percussions sur les zones de population et d&#8217;emploi existantes et pr\u00e9vues (plans officiels approuv\u00e9s).<\/li>\n<li>Veiller \u00e0 ce que les mouvements d&rsquo;\u00e9changeur soient efficaces et directs, et permettent de r\u00e9soudre les probl\u00e8mes et de saisir les opportunit\u00e9s en mati\u00e8re de transport.<\/li>\n<\/ol>\n<p>Une \u00e9valuation d\u00e9taill\u00e9e de la pr\u00e9s\u00e9lection des trac\u00e9s viables a \u00e9t\u00e9 lanc\u00e9e afin de s\u00e9lectionner le trac\u00e9 privil\u00e9gi\u00e9 sur le plan technique. L&rsquo;\u00e9valuation comprenait l&rsquo;identification des avantages et des inconv\u00e9nients des diff\u00e9rentes solutions retenues dans la pr\u00e9s\u00e9lection.<\/p>\n<p>Compte tenu des commentaires re\u00e7us sur le trac\u00e9 privil\u00e9gi\u00e9 sur le plan technique, des am\u00e9liorations suppl\u00e9mentaires ont \u00e9t\u00e9 apport\u00e9es afin de minimiser davantage les r\u00e9percussions potentielles, et un trac\u00e9 privil\u00e9gi\u00e9 a \u00e9t\u00e9 s\u00e9lectionn\u00e9.<\/p>\n<p>Enfin, le chapitre 3 examine les diff\u00e9rentes options de conception qui ont \u00e9t\u00e9 envisag\u00e9es au cours des premi\u00e8res \u00e9tapes de la conception pr\u00e9liminaire, notamment les am\u00e9liorations apport\u00e9es au trac\u00e9, les configurations des \u00e9changeurs, les principaux franchissements de cours d&rsquo;eau, la gestion du drainage et des eaux pluviales, ainsi que les installations de soutien suppl\u00e9mentaires.<\/p>\n\t\t\t\tChapitre 4 : Conception pr\u00e9liminaire\n\t\t\t\t\t<p>Le chapitre 4 pr\u00e9sente un aper\u00e7u complet de la conception pr\u00e9liminaire du projet de l&rsquo;autoroute 413, en d\u00e9crivant les principaux \u00e9l\u00e9ments d&rsquo;infrastructure. Il comprend des descriptions des \u00e9l\u00e9ments importants tels que les \u00e9changeurs (o\u00f9 les autoroutes rejoignent d&rsquo;autres autoroutes ou routes principales), les croisements routiers et d&rsquo;autres installations connexes.<\/p>\n<p>Ce chapitre aborde \u00e9galement les aspects techniques de l&rsquo;autoroute, notamment la circulation, la conception des fondations, la planification et la gestion de la construction afin d&rsquo;\u00e9viter les perturbations, ainsi que les consid\u00e9rations environnementales.<\/p>\n\t\t\t\tChapitre 5 : R\u00e9percussions et mesures d&rsquo;att\u00e9nuation\n\t\t\t\t\t<p>Le chapitre 5 pr\u00e9sente un aper\u00e7u des r\u00e9percussions potentielles et des mesures d&rsquo;att\u00e9nuation associ\u00e9es au projet de l&rsquo;autoroute 413. Ce chapitre comprend un tableau organis\u00e9 par discipline et d\u00e9crit comment les r\u00e9percussions potentielles seront trait\u00e9es gr\u00e2ce \u00e0 diverses mesures d&rsquo;att\u00e9nuation.<\/p>\n\t\t\t\tChapitre 6 : Liste des autorisations potentielles provinciales, f\u00e9d\u00e9rales ou autres\n\t\t\t\t\t<p>Le chapitre 6 explique les diff\u00e9rentes autorisations requises des gouvernements provincial et f\u00e9d\u00e9ral en fonction de la conception pr\u00e9liminaire. Il comprend un tableau qui r\u00e9pertorie les permis, les approbations et les exigences r\u00e9glementaires qui pourraient \u00eatre n\u00e9cessaires pour le projet, class\u00e9s par autorit\u00e9 gouvernementale responsable.<\/p>\n<p>Le chapitre 6 met \u00e9galement en \u00e9vidence le protocole d&rsquo;entente sur l&rsquo;\u00e9valuation des effets dans les zones de comp\u00e9tence f\u00e9d\u00e9rale du projet de l&rsquo;autoroute 413, qui a \u00e9t\u00e9 \u00e9tabli afin de faciliter la collaboration entre le gouvernement du Canada et la province de l&rsquo;Ontario dans le cadre du projet de l&rsquo;autoroute 413. Cela comprend le groupe de travail bilat\u00e9ral f\u00e9d\u00e9ral-provincial, qui supervise la formation de groupes techniques charg\u00e9s de contribuer \u00e0 l&rsquo;\u00e9valuation des effets et des mesures d&rsquo;att\u00e9nuation et qui coordonne les discussions suppl\u00e9mentaires sur les autorisations requises.<\/p>\n\t\t\t\tChapitre 7 : Consultation et implication des Autochtones\n\t\t\t\t\t<p>Ce chapitre donne un aper\u00e7u du processus de consultation et de mobilisation des communaut\u00e9s autochtones men\u00e9 par le minist\u00e8re des Transports. Il r\u00e9sume les consultations et les activit\u00e9s de mobilisation men\u00e9es aupr\u00e8s des communaut\u00e9s autochtones depuis 2012, notamment une description du plan de consultation des communaut\u00e9s autochtones, une liste des avis de projet et des r\u00e9unions, ainsi qu&rsquo;un r\u00e9sum\u00e9 des commentaires soumis et des pr\u00e9occupations soulev\u00e9es par les communaut\u00e9s autochtones depuis 2012 et les r\u00e9ponses alors apport\u00e9es par le minist\u00e8re des Transports, y compris un r\u00e9sum\u00e9 des commentaires re\u00e7us sur le rapport pr\u00e9liminaire d&rsquo;\u00e9valuation sur les r\u00e9percussions environnementales.<\/p>\n\t\t\t\tChapitre 8 : Consultation et engagement\n\t\t\t\t\t<p>Le chapitre 8 d\u00e9crit le processus de consultation et d&rsquo;engagement men\u00e9 tout au long de l&rsquo;\u00e9laboration du projet de l&rsquo;autoroute 413 et r\u00e9sume les commentaires et les pr\u00e9occupations soulev\u00e9s depuis le 1<sup>er<\/sup> novembre 2012, y compris les commentaires re\u00e7us sur le RERE. Il fournit des d\u00e9tails sur diverses activit\u00e9s d&rsquo;engagement avec les organismes gouvernementaux, les municipalit\u00e9s, les groupes consultatifs, les principaux intervenants et le grand public, ainsi qu&rsquo;un r\u00e9sum\u00e9 des commentaires re\u00e7us et de la r\u00e9ponse du minist\u00e8re des Transports \u00e0 l&rsquo;\u00e9poque. Le chapitre 8 est accompagn\u00e9 de l&rsquo;annexe A, intitul\u00e9e \u00ab Compte rendu des consultations et de l&rsquo;engagement \u00bb.<\/p>\n\t\t\t\tChapitre 9 : Modifications importantes\n\t\t\t\t\t<p>Le chapitre 9 d\u00e9crit les exigences proc\u00e9durales relatives \u00e0 une modification importante conform\u00e9ment \u00e0 la <em>Loi sur l&rsquo;autoroute 413,<\/em> <em>2024<\/em>.<\/p>\n\t\t\t\tChapitre 10 : Prochaines \u00e9tapes\n\t\t\t\t\t<p>Le chapitre 10 d\u00e9crit les principales \u00e9tapes du projet qui suivront l&rsquo;ach\u00e8vement du RERE. Il souligne l&rsquo;engagement \u00e0 poursuivre la consultation et la participation des communaut\u00e9s autochtones et des parties prenantes, afin d&rsquo;assurer la transparence et la collaboration \u00e0 mesure que le projet progresse vers la conception d\u00e9taill\u00e9e.<\/p>\n\t\t\t\tAnnexe A : Compte rendu des consultations et de l&rsquo;engagement\n\t\t\t\t\t<p>L&rsquo;annexe A contient le compte rendu des consultations et de l&rsquo;engagement aupr\u00e8s des organismes gouvernementaux, des municipalit\u00e9s, des groupes consultatifs, des principaux intervenants et du grand public, y compris un r\u00e9sum\u00e9 organis\u00e9 par th\u00e8mes cl\u00e9s de tous les commentaires et pr\u00e9occupations soulev\u00e9s ainsi que les r\u00e9ponses du minist\u00e8re des Transports \u00e0 ce moment-l\u00e0 ; les principaux documents d&rsquo;information ; un r\u00e9sum\u00e9 des principales r\u00e9unions tenues avec les organismes, les municipalit\u00e9s, les groupes d&rsquo;int\u00e9r\u00eat et les autres parties prenantes ; les rapports r\u00e9sumant chacune des quatre s\u00e9ances publiques d&rsquo;information tenues entre novembre 2014 et octobre 2023.<\/p>\n\t\t\t\tAnnexe B : Plans pr\u00e9liminaires\n\t\t\t\t\t<p>L&rsquo;annexe B contient les plans pr\u00e9liminaires de l&rsquo;autoroute 413, qui pr\u00e9sentent la conception g\u00e9n\u00e9rale de l&rsquo;autoroute 413, y compris le trac\u00e9, la configuration des voies, l&#8217;emprise, les pentes, les ouvrages d&rsquo;art, les bassins de r\u00e9tention des eaux pluviales et d&rsquo;autres caract\u00e9ristiques techniques \u00e9labor\u00e9es au stade de la conception pr\u00e9liminaire.<\/p>\n\t\t\t\tAnnexe C : Plan de valeur communautaire\n\t\t\t\t\t<p>L&rsquo;annexe C contient le plan de valeur communautaire (PVC), qui a \u00e9t\u00e9 \u00e9labor\u00e9 \u00e0 partir des commentaires du public et comprend des recommandations de conception identifiant les possibilit\u00e9s d&rsquo;am\u00e9lioration de l&rsquo;am\u00e9nagement paysager et les mesures de protection et de restauration propos\u00e9es pour les \u00e9l\u00e9ments paysagers existants touch\u00e9s par le projet. Le PVC pr\u00e9voit la cr\u00e9ation d&rsquo;espaces verts, la gestion des eaux pluviales, la pr\u00e9servation et l&rsquo;am\u00e9lioration des habitats naturels et la comm\u00e9moration du patrimoine culturel. Des mesures telles que la plantation de v\u00e9g\u00e9tation indig\u00e8ne, la cr\u00e9ation de corridors fauniques et la protection des \u00e9cosyst\u00e8mes existants visent \u00e0 promouvoir la biodiversit\u00e9, la sant\u00e9 \u00e9cologique et \u00e0 am\u00e9liorer l&rsquo;attrait esth\u00e9tique de l&rsquo;autoroute 413.<\/p>\n<h2  id=\"faq\">\n\t\t\tLes FAQ\t<\/h2>\n\t\t\t\tQu&rsquo;est-ce que la Loi sur l&rsquo;autoroute 413 ?\n\t\t\t\t\t<p><em>La Loi sur l&rsquo;autoroute 413, 2024<\/em> est une loi introduite dans le cadre du projet de<em> loi 212 &#8211; Loi de 2024<\/em> sur le d\u00e9sengorgement du r\u00e9seau routier et le gain de temps. <em>La Loi sur l&rsquo;autoroute 413, 2024<\/em> cr\u00e9e un nouveau processus d&rsquo;\u00e9valuation des r\u00e9percussions environnementales du projet de l&rsquo;autoroute 413. Ce processus comprend la publication d&rsquo;un rapport d&rsquo;\u00e9valuation des r\u00e9percussions environnementales (RERE) pr\u00e9liminaire et final, qui comprend une description des \u00e9tudes r\u00e9alis\u00e9es, l&rsquo;\u00e9valuation des r\u00e9percussions, les mesures d&rsquo;att\u00e9nuation propos\u00e9es et un compte rendu des consultations et de l&rsquo;engagement.<\/p>\n<p>Les exigences de<em> la Loi sur l&rsquo;autoroute 413, 2024<\/em> s&rsquo;appuient sur le travail consid\u00e9rable accompli \u00e0 ce jour, notamment les \u00e9tudes environnementales et les consultations et engagements continus, que le promoteur (MTO) a entrepris pour faire avancer les travaux depuis le d\u00e9but du projet en 2007.<\/p>\n\t\t\t\tQuelles \u00e9tudes ont \u00e9t\u00e9 utilis\u00e9es pour \u00e9valuer les r\u00e9percussions environnementales ?\n\t\t\t\t\t<p>Les travaux li\u00e9s au projet de l&rsquo;autoroute 413 ont d\u00e9but\u00e9 en 2007. Depuis, plus de 20 disciplines environnementales et techniques ont \u00e9t\u00e9 \u00e9tudi\u00e9es de mani\u00e8re approfondie dans le cadre de la conception pr\u00e9liminaire et du processus d&rsquo;\u00e9valuation des r\u00e9percussions environnementales. Ces \u00e9tudes comprenaient \u00e0 la fois des travaux pratiques sur le terrain et des recherches documentaires d\u00e9taill\u00e9es, ainsi que des consultations et des activit\u00e9s de mobilisation.<\/p>\n<p>Afin de renforcer la collaboration et l&rsquo;inclusion, des agents de liaison communautaires ont \u00e9t\u00e9 associ\u00e9s au processus. Cette initiative permet aux communaut\u00e9s autochtones de participer activement aux activit\u00e9s sur le terrain, leur offrant ainsi la possibilit\u00e9 d&rsquo;observer directement les travaux sur le site et garantissant que leurs points de vue et leurs priorit\u00e9s sont pris en compte et int\u00e9gr\u00e9s dans les d\u00e9cisions du minist\u00e8re des Transports tout au long du projet.<\/p>\n<p>Les \u00e9tudes environnementales r\u00e9alis\u00e9es pour le projet de l&rsquo;autoroute 413 portent sur les aspects suivants :<\/p>\n<ul>\n<li>Poissons et habitat du poisson<\/li>\n<li>\u00c9cosyst\u00e8mes terrestres<\/li>\n<li>Esp\u00e8ces en p\u00e9ril<\/li>\n<\/ul>\n<p>G\u00e9omorphologie fluviale :<\/p>\n<ul>\n<li>Eaux de surface et eaux souterraines<\/li>\n<li>\u00c9rosion et s\u00e9dimentation<\/li>\n<li>Voies navigables<\/li>\n<li>Paysage<\/li>\n<li>Ressources arch\u00e9ologiques<\/li>\n<li>Ressources patrimoniales b\u00e2ties<\/li>\n<li>Utilisation des terres<\/li>\n<li>Agriculture<\/li>\n<li>Propri\u00e9t\u00e9s contamin\u00e9es et d\u00e9chets<\/li>\n<li>Socio\u00e9conomie<\/li>\n<li>Qualit\u00e9 de l&rsquo;air et \u00e9missions de gaz \u00e0 effet de serre (GES)<\/li>\n<li>Bruit<\/li>\n<li>Changements climatiques<\/li>\n<li>Sant\u00e9 humaine<\/li>\n<li>Cong\u00e8res<\/li>\n<\/ul>\n<p>L&rsquo;environnement b\u00e2ti, les consid\u00e9rations techniques et les infrastructures existantes et futures pris en compte dans le projet de l&rsquo;autoroute 413 comprennent :<\/p>\n<ul>\n<li>G\u00e9otechnique<\/li>\n<li>Transports publics<\/li>\n<li>Eaux de surface et drainage<\/li>\n<li>Transport ferroviaire de marchandises et de banlieue<\/li>\n<li>Transport actif<\/li>\n<li>Services publics<\/li>\n<li>R\u00e9seau routier<\/li>\n<li>Conditions de la circulation<\/li>\n<\/ul>\n\t\t\t\tComment le minist\u00e8re des Transports a-t-il int\u00e9gr\u00e9 les commentaires du public, des parties prenantes et des communaut\u00e9s autochtones dans le choix de la conception pr\u00e9liminaire ?\n\t\t\t\t\t<p>Lors de la deuxi\u00e8me s\u00e9ance d&rsquo;information publique qui s&rsquo;est tenue les 19 et 26 septembre et le 3 octobre 2019, le minist\u00e8re des Transports a pr\u00e9sent\u00e9 le trac\u00e9 privil\u00e9gi\u00e9 afin de recueillir des commentaires sur le trac\u00e9 de l&rsquo;autoroute 413.<\/p>\n<p>Le minist\u00e8re a examin\u00e9 les commentaires recueillis lors de la deuxi\u00e8me s\u00e9ance d&rsquo;information publique et a travaill\u00e9 avec diligence avec les communaut\u00e9s autochtones, les groupes consultatifs, le personnel municipal, les agences et les autres parties prenantes afin d&rsquo;\u00e9tablir le trac\u00e9 privil\u00e9gi\u00e9 pour l&rsquo;autoroute 413 et le corridor de transport en commun, qui a \u00e9t\u00e9 annonc\u00e9 en ao\u00fbt 2020.<\/p>\n<p>Depuis lors, le minist\u00e8re a continu\u00e9 \u00e0 faire progresser le trac\u00e9 privil\u00e9gi\u00e9 afin d&rsquo;\u00e9laborer la conception pr\u00e9liminaire sur la base des nombreuses \u00e9tudes r\u00e9alis\u00e9es pour le projet et des commentaires re\u00e7us.<\/p>\n\t\t\t\tQuel sera l&rsquo;impact de l&rsquo;autoroute 413 sur la circulation ?\n\t\t\t\t\t<p><em>Les usagers pourraient gagner jusqu&rsquo;\u00e0 30 minutes sur leur temps de trajet s&rsquo;ils empruntent l&rsquo;autoroute 413 sur toute sa longueur aux heures de pointe. L&rsquo;autoroute 413 permettra :<\/em><\/p>\n<ul>\n<li>de s<em>timuler le transport de marchandises entre les principaux centres de distribution et les grandes autoroutes telles que les autoroutes 401, 427, 400 et 407ETR <\/em><\/li>\n<li><em>de r\u00e9duire les embouteillages en d\u00e9sengorgeant les routes locales, en particulier celles emprunt\u00e9es par les poids lourds<\/em><\/li>\n<li>d&rsquo;a<em>m\u00e9liorer le r\u00e9seau routier dans le nord-ouest de la r\u00e9gion du Grand Toronto en compl\u00e9tant et en reliant les infrastructures routi\u00e8res existantes.<\/em><\/li>\n<li><em>d&rsquo;am\u00e9liorer l&rsquo;acc\u00e8s aux communaut\u00e9s gr\u00e2ce \u00e0 des \u00e9changeurs strat\u00e9giquement plac\u00e9s<\/em><\/li>\n<li><em>d&rsquo;acc\u00e9l\u00e9rer les interventions d&rsquo;urgence en offrant des itin\u00e9raires plus directs aux ambulances, aux camions de pompiers et \u00e0 la police <\/em><\/li>\n<li>de r<em>elier les services de transport en commun gr\u00e2ce \u00e0 plusieurs aires de covoiturage situ\u00e9es aux \u00e9changeurs<\/em><\/li>\n<\/ul>\n\t\t\t\tQuel sera l&rsquo;impact de l&rsquo;autoroute 413 sur la circulation ?\n\t\t\t\t\t<p><em>Les usagers pourraient gagner jusqu&rsquo;\u00e0 30 minutes sur leur temps de trajet s&rsquo;ils empruntent l&rsquo;autoroute 413 sur toute sa longueur aux heures de pointe. L&rsquo;autoroute 413 permettra :<\/em><\/p>\n<ul>\n<li>de s<em>timuler le transport de marchandises entre les principaux centres de distribution et les grandes autoroutes telles que les autoroutes 401, 427, 400 et 407ETR <\/em><\/li>\n<li><em>de r\u00e9duire les embouteillages en d\u00e9sengorgeant les routes locales, en particulier celles emprunt\u00e9es par les poids lourds<\/em><\/li>\n<li>d&rsquo;a<em>m\u00e9liorer le r\u00e9seau routier dans le nord-ouest de la r\u00e9gion du Grand Toronto en compl\u00e9tant et en reliant les infrastructures routi\u00e8res existantes.<\/em><\/li>\n<li><em>d&rsquo;am\u00e9liorer l&rsquo;acc\u00e8s aux communaut\u00e9s gr\u00e2ce \u00e0 des \u00e9changeurs strat\u00e9giquement plac\u00e9s<\/em><\/li>\n<li><em>d&rsquo;acc\u00e9l\u00e9rer les interventions d&rsquo;urgence en offrant des itin\u00e9raires plus directs aux ambulances, aux camions de pompiers et \u00e0 la police <\/em><\/li>\n<li>de r<em>elier les services de transport en commun gr\u00e2ce \u00e0 plusieurs aires de covoiturage situ\u00e9es aux \u00e9changeurs<\/em><\/li>\n<\/ul>\n\t\t\t\tComment le minist\u00e8re des Transports s&rsquo;assurera-t-il que les mesures d&rsquo;att\u00e9nuation propos\u00e9es seront mises en \u0153uvre ?\n\t\t\t\t\t<p>Le RERE d\u00e9crit les engagements pris en mati\u00e8re de mesures d&rsquo;att\u00e9nuation qui se poursuivront lors des phases de conception futures. Au cours de la conception d\u00e9taill\u00e9e et de la construction, les engagements pris dans le RERE final seront mis en \u0153uvre, notamment :<\/p>\n<ul>\n<li>Obtenir les permis et les autorisations n\u00e9cessaires<\/li>\n<li>Poursuivre la consultation et la collaboration avec les communaut\u00e9s autochtones, les personnes int\u00e9ress\u00e9es et les parties prenantes<\/li>\n<li>Finaliser la conception de l&rsquo;autoroute \u00e9labor\u00e9e lors de la phase de conception pr\u00e9liminaire<\/li>\n<\/ul>\n<p>Au cours de la conception d\u00e9taill\u00e9e, des travaux suppl\u00e9mentaires pourraient \u00eatre n\u00e9cessaires, tels que des lev\u00e9s topographiques, des essais sur les conditions du sol, des \u00e9tudes environnementales, la d\u00e9termination des besoins exacts en mat\u00e9riaux de construction, l&rsquo;\u00e9laboration de la conception pour la mise en \u0153uvre finale de l&rsquo;autoroute et la r\u00e9daction des documents de construction aux fins de la construction de la nouvelle autoroute, des \u00e9changeurs, des ponts, etc. Par cons\u00e9quent, les mesures d&rsquo;att\u00e9nuation d\u00e9crites dans le RERE pourraient \u00eatre mises \u00e0 jour et affin\u00e9es. Les mesures d&rsquo;att\u00e9nuation environnementales identifi\u00e9es lors de la conception pr\u00e9liminaire et confirm\u00e9es lors de la conception d\u00e9taill\u00e9e seront mises en \u0153uvre pendant la construction.<\/p>\n\t\t\t\tLe MTO est-il toujours tenu d&rsquo;obtenir des autorisations et des permis environnementaux pour le projet de l&rsquo;autoroute 413 ?\n\t\t\t\t\t<p><em>La loi sur l&rsquo;autoroute 413 de 2024 <\/em>ne dispense pas le projet de l&rsquo;autoroute 413 d&rsquo;obtenir des autorisations et des permis environnementaux.<\/p>\n<p>Certaines autorisations peuvent \u00eatre requises, notamment, mais sans s&rsquo;y limiter :<\/p>\n<ul>\n<li><em>Loi sur les p\u00eaches (1985), autorisation<\/em><\/li>\n<li><em>Loi sur les esp\u00e8ces en p\u00e9ril (2002), permis<\/em><\/li>\n<li><em>Loi sur les ressources en eau de l&rsquo;Ontario<\/em>, <em>Registre environnemental des activit\u00e9s et des secteurs<\/em><\/li>\n<li><em>Loi sur les esp\u00e8ces en voie de disparition (2007) *<\/em><\/li>\n<li><em>Loi sur le patrimoine de l&rsquo;Ontario (1990)<\/em><\/li>\n<\/ul>\n<p><em>*<\/em>La <em>Loi sur la conservation des esp\u00e8ces<\/em> de 2025 a \u00e9t\u00e9 promulgu\u00e9e dans le cadre du projet de loi 5 (<em>Loi<\/em> <em>pour prot\u00e9ger l&rsquo;Ontario en lib\u00e9rant son \u00e9conomie,<\/em>2025) et, si elle entre en vigueur, remplacera la <em>Loi sur les esp\u00e8ces en voie de disparition<\/em> de 2007. Au moment de la r\u00e9daction du pr\u00e9sent RERE, la <em>Loi sur les esp\u00e8ces en voie de disparition<\/em> de 2007 est toujours en vigueur.<\/p>\n\t\t\t\tQuelles communaut\u00e9s autochtones avez-vous consult\u00e9es tout au long de l&rsquo;\u00e9laboration de la conception pr\u00e9liminaire ?\n\t\t\t\t\t<p>Le minist\u00e8re des Transports a le devoir de consulter et, le cas \u00e9ch\u00e9ant, d&rsquo;accommoder les communaut\u00e9s autochtones lorsqu&rsquo;il envisage des mesures susceptibles d&rsquo;avoir une incidence n\u00e9gative sur leurs droits ancestraux et\/ou issus de trait\u00e9s, qui ont \u00e9t\u00e9 valablement revendiqu\u00e9s ou \u00e9tablis. Le minist\u00e8re des Transports a consult\u00e9 les communaut\u00e9s autochtones au sujet du projet de l&rsquo;autoroute 413 afin de comprendre les r\u00e9percussions potentielles du projet sur les droits ancestraux et\/ou issus de trait\u00e9s, qui ont \u00e9t\u00e9 valablement revendiqu\u00e9s ou \u00e9tablis. Le minist\u00e8re collabore \u00e9galement avec les communaut\u00e9s autochtones qui s&rsquo;int\u00e9ressent \u00e0 la conception pr\u00e9liminaire du projet. En outre, <em>la loi sur l&rsquo;autoroute 413 de 2024<\/em> d\u00e9finit le processus d&rsquo;\u00e9valuation des r\u00e9percussions environnementales potentielles du projet, y compris la cr\u00e9ation d&rsquo;un plan de consultation des Autochtones.<\/p>\n<p>Le minist\u00e8re consulte actuellement :<\/p>\n<ul>\n<li>Premi\u00e8re nation d&rsquo;Alderville<\/li>\n<li>Premi\u00e8re nation de Beausoleil<\/li>\n<li>Premi\u00e8re nation des Chippewas de l&rsquo;\u00eele Georgina<\/li>\n<li>Premi\u00e8re Nation des Chippewas de Rama<\/li>\n<li>Premi\u00e8re Nation de Curve Lake<\/li>\n<li>Premi\u00e8re Nation Hiawatha<\/li>\n<li>Nation Huronne-Wendat (\u00e9galement connue sous le nom de \u00ab Nation Wendat \u00bb ou \u00ab Conseil de la Nation Wendat \u00bb)<\/li>\n<li>Kawartha Nishnawbe<\/li>\n<li>Premi\u00e8re Nation des Mississaugas de l&rsquo;\u00eele Scugog<\/li>\n<li>Premi\u00e8re nation des Mississaugas de Credit<\/li>\n<li>Nation Oneida de Thames<\/li>\n<li>Communaut\u00e9 des Six Nations\n<ul>\n<li>Conseil \u00e9lu des Six Nations de Grand River (\u00ab Six Nations de Grand River \u00bb)<\/li>\n<li>Conseil des chefs de la Conf\u00e9d\u00e9ration Haudenosaunee<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Le minist\u00e8re des Transports collabore \u00e9galement avec la Nation m\u00e9tisse de l&rsquo;Ontario sur la base des int\u00e9r\u00eats exprim\u00e9s.<\/p>\n\t\t\t\t\u00c0 quelles occasions le public a-t-il pu donner son avis sur l&rsquo;\u00e9laboration de la conception pr\u00e9liminaire ?\n\t\t\t\t\t<p>Le projet de l&rsquo;autoroute 413 s&rsquo;inscrit dans le cadre d&rsquo;un programme de consultation complet qui encourage l&rsquo;engagement et les commentaires du public, des parties prenantes, des municipalit\u00e9s et des communaut\u00e9s autochtones gr\u00e2ce \u00e0 une s\u00e9rie de m\u00e9thodes de sensibilisation. Ces m\u00e9thodes comprennent les avis du gouvernement de l&rsquo;Ontario, les s\u00e9ances publiques d&rsquo;information, les ateliers communautaires et les r\u00e9unions sur le plan de valeur communautaire, le site internet du projet, la ligne t\u00e9l\u00e9phonique du projet (sans frais), l&rsquo;adresse courriel de l&rsquo;\u00e9quipe du projet, les fiches d&rsquo;information et les bulletins, les r\u00e9unions du groupe consultatif, les pr\u00e9sentations aux conseils municipaux, les r\u00e9unions avec le personnel municipal (ateliers et s\u00e9ances sur des questions sp\u00e9cifiques), les r\u00e9unions avec les parties prenantes techniques (ateliers et r\u00e9unions sur des questions sp\u00e9cifiques) et les r\u00e9unions avec d&rsquo;autres parties int\u00e9ress\u00e9es sur demande (propri\u00e9taires fonciers et autres membres du public, etc.)<\/p>\n<p>Tout au long du processus de consultation pour la conception pr\u00e9liminaire, le minist\u00e8re a re\u00e7u plus de 9 000 commentaires du public, par le biais de l&rsquo;adresse courriel de l&rsquo;\u00e9quipe du projet ou de la ligne t\u00e9l\u00e9phonique du projet (sans frais). Cela s&rsquo;ajoute aux commentaires re\u00e7us par le minist\u00e8re lors de diverses r\u00e9unions avec les communaut\u00e9s, les agences et les parties prenantes, ainsi que lors des quatre s\u00e9ries de s\u00e9ances publiques d&rsquo;information.<\/p>\n\t\t\t\tQue se passe-t-il si la conception d\u00e9taill\u00e9e n&rsquo;est pas conforme au RERE final ?\n\t\t\t\t\t<p>S&rsquo;il y a une modification importante, telle que d\u00e9finie dans <em>la Loi sur l&rsquo;autoroute 413 de 2024<\/em>, par rapport \u00e0 la conception pr\u00e9liminaire illustr\u00e9e dans le RERE final, un addenda sera pr\u00e9par\u00e9 conform\u00e9ment \u00e0 l&rsquo;article 9 de la Loi sur l&rsquo;autoroute 413 de 2024. La proc\u00e9dure est la suivante :<\/p>\n<p><strong>9\u00a0<\/strong>(1) le ministre suit les \u00e9tapes suivantes relativement \u00e0 une modification importante\u00a0:<\/p>\n<ol>\n<li>Il m\u00e8ne les \u00e9tudes de l&rsquo;environnement \u00e0 l&rsquo;\u00e9gard de la modification importante qu&rsquo;il estime appropri\u00e9es.<\/li>\n<li>Il \u00e9value les r\u00e9percussions de la modification importante sur l&rsquo;environnement.<\/li>\n<li>Il pr\u00e9cise la fa\u00e7on dont le minist\u00e8re att\u00e9nuera les r\u00e9percussions n\u00e9gatives relev\u00e9es dans l&rsquo;\u00e9valuation vis\u00e9e \u00e0 la disposition 2.<\/li>\n<li>Il \u00e9tablit un addenda provisoire au rapport final d&rsquo;\u00e9valuation des r\u00e9percussions sur l&rsquo;environnement et un addenda final conform\u00e9ment au pr\u00e9sent article.<\/li>\n<\/ol>\n<p>Toutes les \u00e9tapes d\u00e9crites ci-dessus seront suivies, le cas \u00e9ch\u00e9ant.<\/p>\n\t\t\t\tQuelles sont les prochaines \u00e9tapes maintenant que le RERE est termin\u00e9 ?\n\t\t\t\t\t<p>La publication du RERE final signifie que la phase de conception pr\u00e9liminaire de l&rsquo;autoroute 413 est termin\u00e9e. \u00c0 la suite de cette phase, le projet passera \u00e0 la phase de conception d\u00e9taill\u00e9e, au cours de laquelle les travaux r\u00e9alis\u00e9s pendant la conception pr\u00e9liminaire seront affin\u00e9s et d\u00e9velopp\u00e9s pour atteindre un niveau technique plus complet.<\/p>\n<p>Les travaux de construction se poursuivront dans le cadre des projets de travaux pr\u00e9liminaires, qui comprennent :<\/p>\n<ol>\n<li><strong>Projet de travaux pr\u00e9liminaires n\u00b0 1<\/strong> : remblai \u00e0 l&rsquo;\u00e9changeur 401\/407 ETR\/413 (termin\u00e9)<\/li>\n<li><strong>Projet de travaux pr\u00e9liminaires n\u00b0 2<\/strong> : resurfa\u00e7age et passage souterrain \u00e0 l&rsquo;autoroute 10\/rue Hurontario<\/li>\n<li><strong>Projet de travaux pr\u00e9liminaires n\u00b0 3<\/strong> : passage souterrain \u00e0 promenade Bovaird<\/li>\n<\/ol>\n<p>En plus de ces projets, des travaux plus pouss\u00e9s seront entrepris, notamment le prolongement de l&rsquo;autoroute 410. Pour plus d&rsquo;informations sur ce projet, veuillez consulter le <a href=\"https:\/\/news.ontario.ca\/en\/release\/1006834\/ontario-advancing-work-on-highway-413\">communiqu\u00e9 de presse<\/a> du minist\u00e8re des Transports.<\/p>\n<p>Parall\u00e8lement, les consultations et la collaboration avec les communaut\u00e9s autochtones, les principales parties prenantes et le public se poursuivront. Il en va de m\u00eame pour les permis environnementaux et les travaux de terrain et de recherche cibl\u00e9s, qui sont tous essentiels pour soutenir les prochaines phases du projet.<\/p>\n\t\t\t\tQuel est le calendrier pour l&rsquo;autoroute 413 ?\n\t\t\t\t\t<p>La phase de conception pr\u00e9liminaire de l&rsquo;autoroute 413 devrait \u00eatre achev\u00e9e au d\u00e9but de 2026. Apr\u00e8s la conception pr\u00e9liminaire, l&rsquo;autoroute 413 passera \u00e0 la conception d\u00e9taill\u00e9e.<\/p>\n<p>La conception d\u00e9taill\u00e9e peaufine le travail accompli lors de la conception pr\u00e9liminaire et le d\u00e9veloppe davantage pour atteindre un niveau technique plus complet. Elle \u00e9tablit suffisamment de d\u00e9tails pour mener \u00e0 bien la construction du projet. Au moment de la publication du RERE pr\u00e9liminaire, les options et les \u00e9ch\u00e9anciers pour le phasage et la livraison de la conception d\u00e9taill\u00e9e et de la construction sont \u00e0 l&rsquo;\u00e9tude.<\/p>\n<p>Le calendrier et la dur\u00e9e de la construction de l&rsquo;autoroute d\u00e9pendent de nombreux facteurs, notamment la taille et la complexit\u00e9 du projet, la disponibilit\u00e9 des fonds, la m\u00e9thode d&rsquo;approvisionnement, le calendrier des autorisations et permis environnementaux, ainsi que l&rsquo;acquisition des propri\u00e9t\u00e9s.<\/p>\n<nav aria-label=\"Menu\">\n\t<ul id=\"menu-1-\"><li id=\"menu-item-4983\"><a href=\"#rere\">Rapport d&rsquo;\u00e9valuation des r\u00e9percussions environnementales<\/a><\/li>\n<li id=\"menu-item-5048\"><a href=\"#centre\">Le centre d&rsquo;information<\/a><\/li>\n<li id=\"menu-item-4991\"><a href=\"#naviguer\">Comment naviguer dans le document<\/a><\/li>\n<li id=\"menu-item-4992\"><a href=\"#faq\">Les FAQ<\/a><\/li>\n<\/ul><\/nav>\n\n","protected":false},"excerpt":{"rendered":"<p>12 mars 2026 &#8211; Conform\u00e9ment \u00e0 l&rsquo;article 8 de la loi sur l&rsquo;autoroute 413, 2024, le rapport final d&rsquo;\u00e9valuation des r\u00e9percussions environnementales (RERE) de l&rsquo;autoroute 413 a \u00e9t\u00e9 publi\u00e9. Consultez la page du rapport pour lire le document final.<\/p>\n","protected":false},"author":14,"featured_media":5116,"parent":0,"menu_order":17,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"folder":[],"class_list":["post-4974","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rapport d&#039;\u00e9valuation des r\u00e9percussions environnementales - Autoroute\u202f413<\/title>\n<meta name=\"description\" content=\"Le Rapport d\u2019\u00e9valuation des r\u00e9percussions environnementales (RERE) pr\u00e9liminaire de l\u2019autoroute 413 est d\u00e9sormais disponible pour commentaires\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/highway413.ca\/fr\/rere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rapport d&#039;\u00e9valuation des r\u00e9percussions environnementales - Autoroute\u202f413\" \/>\n<meta property=\"og:description\" content=\"Le Rapport d\u2019\u00e9valuation des r\u00e9percussions environnementales (RERE) pr\u00e9liminaire de l\u2019autoroute 413 est d\u00e9sormais disponible pour commentaires\" \/>\n<meta property=\"og:url\" content=\"https:\/\/highway413.ca\/fr\/rere\/\" \/>\n<meta property=\"og:site_name\" content=\"Autoroute\u202f413\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T19:27:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Highway413-Final-EIAR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2023\" \/>\n\t<meta property=\"og:image:height\" content=\"1294\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/rere\\\/\",\"url\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/rere\\\/\",\"name\":\"Rapport d'\u00e9valuation des r\u00e9percussions environnementales - Autoroute\u202f413\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/rere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/rere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Highway413-Final-EIAR.jpg\",\"datePublished\":\"2025-11-28T20:37:04+00:00\",\"dateModified\":\"2026-04-27T19:27:46+00:00\",\"description\":\"Le Rapport d\u2019\u00e9valuation des r\u00e9percussions environnementales (RERE) pr\u00e9liminaire de l\u2019autoroute 413 est d\u00e9sormais disponible pour commentaires\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/rere\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/highway413.ca\\\/fr\\\/rere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/rere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Highway413-Final-EIAR.jpg\",\"contentUrl\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Highway413-Final-EIAR.jpg\",\"width\":2023,\"height\":1294,\"caption\":\"Page couverture du Rapport final d\u2019\u00e9valuation des impacts environnementaux du projet Highway\u202f413, mars\u202f2026, avec les logos du gouvernement de l\u2019Ontario, de WSP et d\u2019AECOM.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/rere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rapport d&rsquo;\u00e9valuation des r\u00e9percussions environnementales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/\",\"name\":\"Highway 413\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/#organization\",\"name\":\"Highway 413\",\"url\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-413-fr-logo.png\",\"contentUrl\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-413-fr-logo.png\",\"width\":1276,\"height\":271,\"caption\":\"Highway 413\"},\"image\":{\"@id\":\"https:\\\/\\\/highway413.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rapport d'\u00e9valuation des r\u00e9percussions environnementales - Autoroute\u202f413","description":"Le Rapport d\u2019\u00e9valuation des r\u00e9percussions environnementales (RERE) pr\u00e9liminaire de l\u2019autoroute 413 est d\u00e9sormais disponible pour commentaires","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/highway413.ca\/fr\/rere\/","og_locale":"fr_CA","og_type":"article","og_title":"Rapport d'\u00e9valuation des r\u00e9percussions environnementales - Autoroute\u202f413","og_description":"Le Rapport d\u2019\u00e9valuation des r\u00e9percussions environnementales (RERE) pr\u00e9liminaire de l\u2019autoroute 413 est d\u00e9sormais disponible pour commentaires","og_url":"https:\/\/highway413.ca\/fr\/rere\/","og_site_name":"Autoroute\u202f413","article_modified_time":"2026-04-27T19:27:46+00:00","og_image":[{"width":2023,"height":1294,"url":"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Highway413-Final-EIAR.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"22 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/highway413.ca\/fr\/rere\/","url":"https:\/\/highway413.ca\/fr\/rere\/","name":"Rapport d'\u00e9valuation des r\u00e9percussions environnementales - Autoroute\u202f413","isPartOf":{"@id":"https:\/\/highway413.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/highway413.ca\/fr\/rere\/#primaryimage"},"image":{"@id":"https:\/\/highway413.ca\/fr\/rere\/#primaryimage"},"thumbnailUrl":"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Highway413-Final-EIAR.jpg","datePublished":"2025-11-28T20:37:04+00:00","dateModified":"2026-04-27T19:27:46+00:00","description":"Le Rapport d\u2019\u00e9valuation des r\u00e9percussions environnementales (RERE) pr\u00e9liminaire de l\u2019autoroute 413 est d\u00e9sormais disponible pour commentaires","breadcrumb":{"@id":"https:\/\/highway413.ca\/fr\/rere\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/highway413.ca\/fr\/rere\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/highway413.ca\/fr\/rere\/#primaryimage","url":"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Highway413-Final-EIAR.jpg","contentUrl":"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2026\/03\/Highway413-Final-EIAR.jpg","width":2023,"height":1294,"caption":"Page couverture du Rapport final d\u2019\u00e9valuation des impacts environnementaux du projet Highway\u202f413, mars\u202f2026, avec les logos du gouvernement de l\u2019Ontario, de WSP et d\u2019AECOM."},{"@type":"BreadcrumbList","@id":"https:\/\/highway413.ca\/fr\/rere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/highway413.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Rapport d&rsquo;\u00e9valuation des r\u00e9percussions environnementales"}]},{"@type":"WebSite","@id":"https:\/\/highway413.ca\/fr\/#website","url":"https:\/\/highway413.ca\/fr\/","name":"Highway 413","description":"","publisher":{"@id":"https:\/\/highway413.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/highway413.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/highway413.ca\/fr\/#organization","name":"Highway 413","url":"https:\/\/highway413.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/highway413.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2024\/12\/cropped-413-fr-logo.png","contentUrl":"https:\/\/highway413.ca\/fr\/wp-content\/uploads\/2024\/12\/cropped-413-fr-logo.png","width":1276,"height":271,"caption":"Highway 413"},"image":{"@id":"https:\/\/highway413.ca\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/highway413.ca\/fr\/wp-json\/wp\/v2\/pages\/4974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/highway413.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/highway413.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/highway413.ca\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/highway413.ca\/fr\/wp-json\/wp\/v2\/comments?post=4974"}],"version-history":[{"count":20,"href":"https:\/\/highway413.ca\/fr\/wp-json\/wp\/v2\/pages\/4974\/revisions"}],"predecessor-version":[{"id":5142,"href":"https:\/\/highway413.ca\/fr\/wp-json\/wp\/v2\/pages\/4974\/revisions\/5142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/highway413.ca\/fr\/wp-json\/wp\/v2\/media\/5116"}],"wp:attachment":[{"href":"https:\/\/highway413.ca\/fr\/wp-json\/wp\/v2\/media?parent=4974"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/highway413.ca\/fr\/wp-json\/wp\/v2\/folder?post=4974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}